{"id":702,"date":"2017-05-13T08:03:30","date_gmt":"2017-05-13T08:03:30","guid":{"rendered":"http:\/\/wongsanit-ashram.org\/2019\/?p=702"},"modified":"2019-02-01T01:00:46","modified_gmt":"2019-02-01T01:00:46","slug":"trawainaiduangjit10","status":"publish","type":"post","link":"https:\/\/wongsanit-ashram.org\/2019\/2017\/05\/13\/trawainaiduangjit10\/","title":{"rendered":"\u0e15\u0e23\u0e32\u0e44\u0e27\u0e49\u0e43\u0e19\u0e14\u0e27\u0e07\u0e08\u0e34\u0e15 \u0e15\u0e2d\u0e1910"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"702\" class=\"elementor elementor-702 elementor-bc-flex-widget\">\n\t\t\t\t\t\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-top-section elementor-element elementor-element-0ca8c20 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-eae-slider=\"17881\" data-id=\"0ca8c20\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-dcd11ee\" data-eae-slider=\"8342\" data-id=\"dcd11ee\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fbc364f elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"fbc364f\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.18.0 - 20-12-2023 *\/\n.elementor-widget-divider{--divider-border-style:none;--divider-border-width:1px;--divider-color:#0c0d0e;--divider-icon-size:20px;--divider-element-spacing:10px;--divider-pattern-height:24px;--divider-pattern-size:20px;--divider-pattern-url:none;--divider-pattern-repeat:repeat-x}.elementor-widget-divider .elementor-divider{display:flex}.elementor-widget-divider .elementor-divider__text{font-size:15px;line-height:1;max-width:95%}.elementor-widget-divider .elementor-divider__element{margin:0 var(--divider-element-spacing);flex-shrink:0}.elementor-widget-divider .elementor-icon{font-size:var(--divider-icon-size)}.elementor-widget-divider .elementor-divider-separator{display:flex;margin:0;direction:ltr}.elementor-widget-divider--view-line_icon .elementor-divider-separator,.elementor-widget-divider--view-line_text .elementor-divider-separator{align-items:center}.elementor-widget-divider--view-line_icon .elementor-divider-separator:after,.elementor-widget-divider--view-line_icon .elementor-divider-separator:before,.elementor-widget-divider--view-line_text .elementor-divider-separator:after,.elementor-widget-divider--view-line_text .elementor-divider-separator:before{display:block;content:\"\";border-bottom:0;flex-grow:1;border-top:var(--divider-border-width) var(--divider-border-style) var(--divider-color)}.elementor-widget-divider--element-align-left .elementor-divider .elementor-divider-separator>.elementor-divider__svg:first-of-type{flex-grow:0;flex-shrink:100}.elementor-widget-divider--element-align-left .elementor-divider-separator:before{content:none}.elementor-widget-divider--element-align-left .elementor-divider__element{margin-left:0}.elementor-widget-divider--element-align-right .elementor-divider .elementor-divider-separator>.elementor-divider__svg:last-of-type{flex-grow:0;flex-shrink:100}.elementor-widget-divider--element-align-right .elementor-divider-separator:after{content:none}.elementor-widget-divider--element-align-right .elementor-divider__element{margin-right:0}.elementor-widget-divider:not(.elementor-widget-divider--view-line_text):not(.elementor-widget-divider--view-line_icon) .elementor-divider-separator{border-top:var(--divider-border-width) var(--divider-border-style) var(--divider-color)}.elementor-widget-divider--separator-type-pattern{--divider-border-style:none}.elementor-widget-divider--separator-type-pattern.elementor-widget-divider--view-line .elementor-divider-separator,.elementor-widget-divider--separator-type-pattern:not(.elementor-widget-divider--view-line) .elementor-divider-separator:after,.elementor-widget-divider--separator-type-pattern:not(.elementor-widget-divider--view-line) .elementor-divider-separator:before,.elementor-widget-divider--separator-type-pattern:not([class*=elementor-widget-divider--view]) .elementor-divider-separator{width:100%;min-height:var(--divider-pattern-height);-webkit-mask-size:var(--divider-pattern-size) 100%;mask-size:var(--divider-pattern-size) 100%;-webkit-mask-repeat:var(--divider-pattern-repeat);mask-repeat:var(--divider-pattern-repeat);background-color:var(--divider-color);-webkit-mask-image:var(--divider-pattern-url);mask-image:var(--divider-pattern-url)}.elementor-widget-divider--no-spacing{--divider-pattern-size:auto}.elementor-widget-divider--bg-round{--divider-pattern-repeat:round}.rtl .elementor-widget-divider .elementor-divider__text{direction:rtl}.e-con-inner>.elementor-widget-divider,.e-con>.elementor-widget-divider{width:var(--container-widget-width,100%);--flex-grow:var(--container-widget-flex-grow)}<\/style>\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-b20774b\" data-eae-slider=\"7351\" data-id=\"b20774b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-120d089 elementor-widget elementor-widget-image\" data-id=\"120d089\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.18.0 - 20-12-2023 *\/\n.elementor-widget-image{text-align:center}.elementor-widget-image a{display:inline-block}.elementor-widget-image a img[src$=\".svg\"]{width:48px}.elementor-widget-image img{vertical-align:middle;display:inline-block}<\/style>\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"780\" height=\"780\" src=\"https:\/\/wongsanit-ashram.org\/2019\/wp-content\/uploads\/2019\/01\/CV_Ashram_S-2.jpg\" class=\"attachment-large size-large wp-image-664\" alt=\"\" srcset=\"https:\/\/wongsanit-ashram.org\/2019\/wp-content\/uploads\/2019\/01\/CV_Ashram_S-2.jpg 780w, https:\/\/wongsanit-ashram.org\/2019\/wp-content\/uploads\/2019\/01\/CV_Ashram_S-2-150x150.jpg 150w, https:\/\/wongsanit-ashram.org\/2019\/wp-content\/uploads\/2019\/01\/CV_Ashram_S-2-300x300.jpg 300w, https:\/\/wongsanit-ashram.org\/2019\/wp-content\/uploads\/2019\/01\/CV_Ashram_S-2-768x768.jpg 768w, https:\/\/wongsanit-ashram.org\/2019\/wp-content\/uploads\/2019\/01\/CV_Ashram_S-2-640x640.jpg 640w, https:\/\/wongsanit-ashram.org\/2019\/wp-content\/uploads\/2019\/01\/CV_Ashram_S-2-533x533.jpg 533w, https:\/\/wongsanit-ashram.org\/2019\/wp-content\/uploads\/2019\/01\/CV_Ashram_S-2-725x725.jpg 725w, https:\/\/wongsanit-ashram.org\/2019\/wp-content\/uploads\/2019\/01\/CV_Ashram_S-2-50x50.jpg 50w\" sizes=\"(max-width: 780px) 100vw, 780px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-f71472a\" data-eae-slider=\"74916\" data-id=\"f71472a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a246881 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"a246881\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-top-section elementor-element elementor-element-0a9ec4a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-eae-slider=\"12207\" data-id=\"0a9ec4a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4d33964\" data-eae-slider=\"6538\" data-id=\"4d33964\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bbaf4dc elementor-widget elementor-widget-text-editor\" data-id=\"bbaf4dc\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.18.0 - 20-12-2023 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<table><tbody><tr><td><h2 align=\"left\">\u0e15\u0e2d\u0e19\u0e17\u0e35\u0e48 \u0e51\u0e50 \u0e17\u0e14\u0e2a\u0e2d\u0e1a<\/h2><p>\u0e17\u0e35\u0e48\u0e21\u0e32 : \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d \u0e15\u0e23\u0e32\u0e44\u0e27\u0e49\u0e43\u0e19\u0e14\u0e27\u0e07\u0e08\u0e34\u0e15 \u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e23\u0e32\u0e27\u0e2d\u0e32\u0e28\u0e23\u0e21\u0e27\u0e07\u0e28\u0e4c\u0e2a\u0e19\u0e34\u0e17\u0e22\u0e38\u0e04\u0e1a\u0e38\u0e01\u0e40\u0e1a\u0e34\u0e01 \u0e40\u0e02\u0e35\u0e22\u0e19\u0e42\u0e14\u0e22 \u0e28\u0e34\u0e23\u0e34\u0e1e\u0e23 \u0e42\u0e0a\u0e15\u0e34\u0e0a\u0e31\u0e0a\u0e27\u0e32\u0e25\u0e22\u0e4c\u0e01\u0e38\u0e25<\/p><hr \/><\/td><\/tr><tr><td><p><img decoding=\"async\" class=\"alignleft\" src=\"http:\/\/wongsanit-ashram.org\/2019\/wp-content\/uploads\/2019\/01\/046.jpg\" alt=\"046\" width=\"300\" height=\"273\" \/>\u0e19\u0e49\u0e33\u0e43\u0e19\u0e04\u0e25\u0e2d\u0e07\u0e40\u0e23\u0e34\u0e48\u0e21\u0e44\u0e2b\u0e25\u0e40\u0e23\u0e47\u0e27\u0e41\u0e25\u0e30\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e19\u0e49\u0e33\u0e2a\u0e39\u0e07\u0e02\u0e36\u0e49\u0e19\u0e17\u0e38\u0e01\u0e27\u0e31\u0e19 \u0e40\u0e23\u0e32\u0e40\u0e23\u0e34\u0e48\u0e21\u0e16\u0e39\u0e01\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34\u0e17\u0e14\u0e2a\u0e2d\u0e1a\u0e1d\u0e35\u0e21\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e1e\u0e32\u0e22\u0e40\u0e23\u0e37\u0e2d\u0e27\u0e48\u0e32\u0e43\u0e0a\u0e49\u0e01\u0e32\u0e23\u0e44\u0e14\u0e49\u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e31\u0e07\u0e15\u0e2d\u0e19\u0e19\u0e35\u0e49\u0e40\u0e23\u0e32\u0e21\u0e35\u0e40\u0e23\u0e37\u0e2d\u0e25\u0e33\u0e40\u0e25\u0e47\u0e01\u0e17\u0e35\u0e48\u0e08\u0e49\u0e32\u0e07\u0e0a\u0e48\u0e32\u0e07\u0e15\u0e48\u0e2d 1 \u0e25\u0e33 \u0e01\u0e48\u0e2d\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e19\u0e35\u0e49\u0e40\u0e23\u0e32\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e40\u0e23\u0e37\u0e2d\u0e1b\u0e49\u0e32\u0e41\u0e14\u0e07 \u0e41\u0e23\u0e01\u0e46 \u0e17\u0e35\u0e48\u0e40\u0e23\u0e34\u0e48\u0e21\u0e21\u0e35\u0e01\u0e23\u0e30\u0e41\u0e2a\u0e19\u0e49\u0e33\u0e40\u0e0a\u0e35\u0e48\u0e22\u0e27\u0e40\u0e23\u0e32\u0e01\u0e47\u0e44\u0e21\u0e48\u0e04\u0e48\u0e2d\u0e22\u0e21\u0e31\u0e48\u0e19\u0e43\u0e08\u0e19\u0e31\u0e01\u0e27\u0e48\u0e32\u0e08\u0e30\u0e1e\u0e32\u0e22\u0e40\u0e23\u0e37\u0e2d\u0e02\u0e49\u0e32\u0e21\u0e1d\u0e31\u0e48\u0e07\u0e44\u0e14\u0e49\u0e15\u0e23\u0e07\u0e08\u0e38\u0e14\u0e44\u0e2b\u0e19 \u0e17\u0e35\u0e48\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e08\u0e30\u0e1a\u0e31\u0e07\u0e04\u0e31\u0e1a\u0e40\u0e23\u0e37\u0e2d\u0e40\u0e02\u0e49\u0e32\u0e1d\u0e31\u0e48\u0e07\u0e44\u0e14\u0e49\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48 \u0e41\u0e15\u0e48\u0e43\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e01\u0e47\u0e17\u0e33\u0e44\u0e14\u0e49 \u0e21\u0e35\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e1a\u0e32\u0e07\u0e04\u0e19\u0e21\u0e32\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e43\u0e19\u0e0a\u0e48\u0e27\u0e07\u0e19\u0e35\u0e49\u0e41\u0e25\u0e30\u0e44\u0e21\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e1a\u0e31\u0e07\u0e04\u0e31\u0e1a\u0e40\u0e23\u0e37\u0e2d\u0e40\u0e02\u0e49\u0e32\u0e1d\u0e31\u0e48\u0e07\u0e44\u0e14\u0e49\u0e1e\u0e27\u0e01\u0e40\u0e23\u0e32\u0e15\u0e49\u0e2d\u0e07\u0e04\u0e2d\u0e22\u0e40\u0e2d\u0e32\u0e43\u0e08\u0e0a\u0e48\u0e27\u0e22 \u0e15\u0e30\u0e42\u0e01\u0e19\u0e1a\u0e2d\u0e01\u0e27\u0e34\u0e18\u0e35\u0e1e\u0e32\u0e22\u0e2d\u0e22\u0e39\u0e48\u0e0a\u0e32\u0e22\u0e04\u0e25\u0e2d\u0e07<\/p><p>\u201c\u0e40\u0e2d\u0e49\u0e32! \u0e1e\u0e32\u0e22\u0e17\u0e32\u0e07\u0e0b\u0e49\u0e32\u0e22 \u0e0b\u0e49\u0e32\u0e22 \u0e0b\u0e49\u0e32\u0e22 \u0e04\u0e23\u0e32\u0e27\u0e19\u0e35\u0e49\u0e02\u0e27\u0e32 \u0e02\u0e27\u0e32 \u0e02\u0e27\u0e32 \u0e2d\u0e22\u0e48\u0e32\u0e15\u0e01\u0e43\u0e08&#8230;\u201d<\/p><p>\u0e01\u0e27\u0e48\u0e32\u0e08\u0e30\u0e17\u0e33\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e40\u0e23\u0e37\u0e2d\u0e01\u0e47\u0e2d\u0e32\u0e08\u0e08\u0e30\u0e40\u0e02\u0e49\u0e32\u0e08\u0e2d\u0e14\u0e44\u0e14\u0e49\u0e40\u0e25\u0e22\u0e08\u0e38\u0e14\u0e17\u0e35\u0e48 \u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e44\u0e1b\u0e2a\u0e31\u0e01\u0e2a\u0e32\u0e21\u0e2a\u0e34\u0e1a\u0e40\u0e21\u0e15\u0e23 \u0e15\u0e49\u0e2d\u0e07\u0e40\u0e14\u0e34\u0e19\u0e1a\u0e19\u0e15\u0e25\u0e34\u0e48\u0e07\u0e08\u0e39\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e01\u0e25\u0e31\u0e1a\u0e21\u0e32<\/p><p>\u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e01\u0e23\u0e30\u0e41\u0e2a\u0e19\u0e49\u0e33\u0e40\u0e0a\u0e35\u0e48\u0e22\u0e27\u0e01\u0e23\u0e32\u0e01\u0e41\u0e25\u0e49\u0e27 \u0e22\u0e31\u0e07\u0e21\u0e35\u0e01\u0e23\u0e30\u0e41\u0e2a\u0e25\u0e21\u0e17\u0e35\u0e48\u0e14\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e01\u0e31\u0e19\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e17\u0e14\u0e2a\u0e2d\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e40\u0e02\u0e49\u0e21\u0e41\u0e02\u0e47\u0e07\u0e02\u0e2d\u0e07\u0e40\u0e23\u0e32 \u0e40\u0e23\u0e32\u0e44\u0e14\u0e49\u0e1f\u0e31\u0e07\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e23\u0e32\u0e27\u0e02\u0e2d\u0e07\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e2b\u0e25\u0e32\u0e22\u0e23\u0e32\u0e22\u0e17\u0e35\u0e48\u0e40\u0e04\u0e22\u0e16\u0e39\u0e01\u0e25\u0e21\u0e2b\u0e21\u0e38\u0e19\u0e1e\u0e31\u0e14\u0e1a\u0e49\u0e32\u0e19\u0e1e\u0e31\u0e07 \u0e25\u0e21\u0e2b\u0e2d\u0e1a\u0e40\u0e2d\u0e32\u0e2a\u0e31\u0e07\u0e01\u0e30\u0e2a\u0e35\u0e1b\u0e25\u0e34\u0e27\u0e44\u0e1b\u0e44\u0e01\u0e25\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e34\u0e42\u0e25\u0e40\u0e21\u0e15\u0e23 \u0e1a\u0e49\u0e32\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e2b\u0e48\u0e32\u0e07\u0e40\u0e23\u0e32\u0e01\u0e34\u0e42\u0e25\u0e40\u0e21\u0e15\u0e23\u0e04\u0e23\u0e36\u0e48\u0e07\u0e16\u0e39\u0e01\u0e25\u0e21\u0e2b\u0e2d\u0e1a\u0e0b\u0e49\u0e33\u0e16\u0e36\u0e07\u0e2a\u0e2d\u0e07\u0e1b\u0e35\u0e15\u0e34\u0e14\u0e01\u0e31\u0e19 \u0e40\u0e23\u0e32\u0e40\u0e1d\u0e49\u0e32\u0e41\u0e15\u0e48\u0e2b\u0e27\u0e32\u0e14\u0e2b\u0e27\u0e31\u0e48\u0e19\u0e27\u0e48\u0e32\u0e42\u0e04\u0e01\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e23\u0e32\u0e2a\u0e39\u0e07\u0e01\u0e27\u0e48\u0e32\u0e43\u0e04\u0e23\u0e14\u0e34\u0e19\u0e22\u0e31\u0e07\u0e43\u0e2b\u0e21\u0e48\u0e08\u0e30\u0e22\u0e36\u0e14\u0e40\u0e2a\u0e32\u0e1a\u0e49\u0e32\u0e19\u0e44\u0e14\u0e49\u0e41\u0e19\u0e48\u0e19\u0e41\u0e04\u0e48\u0e44\u0e2b\u0e19\u0e01\u0e47\u0e44\u0e21\u0e48\u0e23\u0e39\u0e49 \u0e15\u0e49\u0e19\u0e44\u0e21\u0e49\u0e01\u0e47\u0e22\u0e31\u0e07\u0e44\u0e21\u0e48\u0e42\u0e15\u0e1e\u0e2d\u0e08\u0e30\u0e1a\u0e31\u0e07\u0e25\u0e21 \u0e1a\u0e49\u0e32\u0e19\u0e40\u0e23\u0e32\u0e40\u0e1b\u0e25\u0e48\u0e32\u0e40\u0e1b\u0e25\u0e37\u0e2d\u0e22\u0e2a\u0e39\u0e07\u0e40\u0e14\u0e48\u0e19\u0e42\u0e14\u0e14\u0e40\u0e14\u0e35\u0e48\u0e22\u0e27\u0e2d\u0e22\u0e39\u0e48\u0e01\u0e25\u0e32\u0e07\u0e17\u0e38\u0e48\u0e07\u0e01\u0e27\u0e49\u0e32\u0e07<\/p><p>\u0e41\u0e25\u0e30\u0e41\u0e25\u0e49\u0e27\u0e40\u0e27\u0e25\u0e32\u0e01\u0e47\u0e21\u0e32\u0e16\u0e36\u0e07 \u0e40\u0e1e\u0e35\u0e22\u0e07\u0e40\u0e23\u0e34\u0e48\u0e21\u0e24\u0e14\u0e39\u0e01\u0e48\u0e2d\u0e19\u0e1d\u0e19\u0e15\u0e01\u0e17\u0e38\u0e01\u0e04\u0e23\u0e31\u0e49\u0e07\u0e08\u0e30\u0e21\u0e35\u0e25\u0e21\u0e19\u0e33\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e19\u0e1e\u0e31\u0e14\u0e41\u0e23\u0e07\u0e08\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e2a\u0e31\u0e48\u0e19\u0e44\u0e2b\u0e27 \u0e02\u0e49\u0e32\u0e27\u0e02\u0e2d\u0e07\u0e1b\u0e25\u0e34\u0e27\u0e01\u0e23\u0e30\u0e08\u0e32\u0e22 \u0e41\u0e25\u0e49\u0e27\u0e01\u0e47\u0e41\u0e1b\u0e25\u0e01\u0e40\u0e02\u0e32\u0e0a\u0e2d\u0e1a\u0e21\u0e32\u0e01\u0e25\u0e32\u0e07\u0e04\u0e37\u0e19\u0e40\u0e2a\u0e35\u0e22\u0e14\u0e49\u0e27\u0e22\u0e2a\u0e34 \u0e2b\u0e25\u0e32\u0e22\u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48\u0e40\u0e23\u0e32\u0e15\u0e49\u0e2d\u0e07\u0e15\u0e37\u0e48\u0e19\u0e15\u0e35\u0e2a\u0e2d\u0e07\u0e15\u0e35\u0e2a\u0e32\u0e21\u0e14\u0e49\u0e27\u0e22\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e25\u0e21\u0e04\u0e33\u0e23\u0e32\u0e21\u0e01\u0e23\u0e30\u0e42\u0e0a\u0e01\u0e2d\u0e22\u0e39\u0e48\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e23\u0e38\u0e19\u0e41\u0e23\u0e07\u0e08\u0e19\u0e40\u0e23\u0e32\u0e44\u0e21\u0e48\u0e01\u0e25\u0e49\u0e32\u0e19\u0e2d\u0e19\u0e15\u0e48\u0e2d \u0e15\u0e49\u0e2d\u0e07\u0e25\u0e38\u0e01\u0e21\u0e32\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e1e\u0e23\u0e49\u0e2d\u0e21 \u0e16\u0e32\u0e21\u0e01\u0e31\u0e19\u0e40\u0e2d\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e40\u0e2a\u0e21\u0e2d\u0e27\u0e48\u0e32\u0e1a\u0e49\u0e32\u0e19\u0e17\u0e35\u0e48\u0e21\u0e38\u0e07\u0e14\u0e49\u0e27\u0e22\u0e15\u0e31\u0e1a\u0e08\u0e32\u0e01\u0e2b\u0e25\u0e31\u0e07\u0e19\u0e49\u0e2d\u0e22\u0e02\u0e2d\u0e07\u0e40\u0e23\u0e32\u0e08\u0e30\u0e17\u0e32\u0e19\u0e41\u0e23\u0e07\u0e25\u0e21\u0e44\u0e2b\u0e27\u0e44\u0e2b\u0e21\u0e2b\u0e19\u0e2d \u0e08\u0e30\u0e2d\u0e22\u0e39\u0e48\u0e1a\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e01\u0e47\u0e01\u0e25\u0e31\u0e27\u0e08\u0e30\u0e16\u0e39\u0e01\u0e25\u0e21\u0e2b\u0e2d\u0e1a\u0e44\u0e1b\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e1a\u0e1a\u0e49\u0e32\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48\u0e01\u0e47\u0e40\u0e01\u0e23\u0e07\u0e27\u0e48\u0e32\u0e42\u0e23\u0e07\u0e2d\u0e40\u0e19\u0e01\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e17\u0e35\u0e48\u0e1b\u0e25\u0e39\u0e01\u0e44\u0e27\u0e49\u0e43\u0e01\u0e25\u0e49\u0e1a\u0e49\u0e32\u0e19\u0e08\u0e30\u0e25\u0e49\u0e21\u0e21\u0e32\u0e17\u0e31\u0e1a \u0e14\u0e39\u0e21\u0e31\u0e19\u0e2a\u0e31\u0e48\u0e19\u0e04\u0e25\u0e2d\u0e19\u0e44\u0e2b\u0e27\u0e1e\u0e30\u0e40\u0e22\u0e34\u0e1a\u0e1e\u0e30\u0e22\u0e32\u0e1a\u0e19\u0e48\u0e32\u0e01\u0e25\u0e31\u0e27\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e40\u0e01\u0e34\u0e19 \u0e04\u0e23\u0e31\u0e49\u0e19\u0e25\u0e2d\u0e07\u0e25\u0e07\u0e21\u0e32\u0e2d\u0e22\u0e39\u0e48\u0e02\u0e49\u0e32\u0e07\u0e25\u0e48\u0e32\u0e07\u0e01\u0e47\u0e16\u0e39\u0e01\u0e1d\u0e19\u0e08\u0e19\u0e40\u0e1b\u0e35\u0e22\u0e01\u0e1b\u0e2d\u0e19\u0e41\u0e25\u0e49\u0e27\u0e01\u0e47\u0e17\u0e32\u0e19\u0e41\u0e23\u0e07\u0e25\u0e21\u0e44\u0e21\u0e48\u0e2a\u0e39\u0e49\u0e08\u0e30\u0e44\u0e2b\u0e27 \u0e2b\u0e19\u0e32\u0e27\u0e01\u0e47\u0e2b\u0e19\u0e32\u0e27 \u0e2a\u0e38\u0e14\u0e17\u0e49\u0e32\u0e22\u0e01\u0e47\u0e01\u0e25\u0e31\u0e1a\u0e02\u0e36\u0e49\u0e19\u0e44\u0e1b\u0e2d\u0e22\u0e39\u0e48\u0e1a\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e2d\u0e35\u0e01 \u0e25\u0e21\u0e41\u0e23\u0e07\u0e02\u0e36\u0e49\u0e19\u0e17\u0e38\u0e01\u0e27\u0e31\u0e19\u0e17\u0e38\u0e01\u0e04\u0e37\u0e19 \u0e40\u0e23\u0e32\u0e15\u0e49\u0e2d\u0e07\u0e15\u0e37\u0e48\u0e19\u0e15\u0e32\u0e23\u0e2d\u0e08\u0e19\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e01\u0e23\u0e30\u0e42\u0e0a\u0e01\u0e04\u0e33\u0e23\u0e32\u0e21\u0e04\u0e48\u0e2d\u0e22\u0e46 \u0e40\u0e1a\u0e32\u0e25\u0e07\u0e08\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e04\u0e23\u0e27\u0e0d\u0e04\u0e23\u0e32\u0e07\u0e41\u0e25\u0e30\u0e2a\u0e07\u0e1a\u0e08\u0e36\u0e07\u0e19\u0e2d\u0e19\u0e15\u0e48\u0e2d \u0e1a\u0e32\u0e07\u0e04\u0e37\u0e19\u0e40\u0e02\u0e32\u0e01\u0e47\u0e21\u0e32\u0e40\u0e22\u0e37\u0e2d\u0e19\u0e01\u0e31\u0e19\u0e2a\u0e2d\u0e07\u0e23\u0e30\u0e25\u0e2d\u0e01\u0e2a\u0e32\u0e21\u0e23\u0e30\u0e25\u0e2d\u0e01\u0e08\u0e19\u0e43\u0e01\u0e25\u0e49\u0e23\u0e38\u0e48\u0e07\u0e08\u0e36\u0e07\u0e40\u0e25\u0e34\u0e01\u0e23\u0e32\u0e44\u0e1b\u0e04\u0e07\u0e01\u0e25\u0e31\u0e27\u0e40\u0e23\u0e32\u0e40\u0e2b\u0e07\u0e32<\/p><p>\u0e25\u0e21\u0e21\u0e32\u0e41\u0e23\u0e07\u0e15\u0e2d\u0e19\u0e15\u0e49\u0e19\u0e01\u0e31\u0e1a\u0e1b\u0e25\u0e32\u0e22\u0e24\u0e14\u0e39\u0e1d\u0e19 \u0e0a\u0e48\u0e27\u0e07\u0e01\u0e25\u0e32\u0e07\u0e24\u0e14\u0e39\u0e08\u0e30\u0e2b\u0e19\u0e31\u0e01\u0e44\u0e1b\u0e17\u0e32\u0e07\u0e1d\u0e19 \u0e1a\u0e32\u0e07\u0e04\u0e23\u0e31\u0e49\u0e07\u0e01\u0e47\u0e15\u0e01\u0e42\u0e14\u0e22\u0e44\u0e21\u0e48\u0e21\u0e35\u0e25\u0e21\u0e19\u0e33 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e19\u0e35\u0e49\u0e40\u0e23\u0e32\u0e0a\u0e2d\u0e1a \u0e41\u0e15\u0e48\u0e42\u0e14\u0e22\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b\u0e41\u0e25\u0e49\u0e27\u0e01\u0e47\u0e21\u0e35\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e48\u0e32\u0e40\u0e1a\u0e37\u0e48\u0e2d\u0e2d\u0e22\u0e39\u0e48 \u0e04\u0e37\u0e2d\u0e14\u0e34\u0e19\u0e17\u0e35\u0e48\u0e19\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e14\u0e34\u0e19\u0e40\u0e2b\u0e19\u0e35\u0e22\u0e27 \u0e0a\u0e19\u0e34\u0e14\u0e19\u0e33\u0e21\u0e32\u0e1b\u0e31\u0e49\u0e19\u0e40\u0e15\u0e32\u0e44\u0e14\u0e49\u0e42\u0e14\u0e22\u0e40\u0e2a\u0e35\u0e22\u0e40\u0e27\u0e25\u0e32\u0e19\u0e27\u0e14\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e44\u0e21\u0e48\u0e19\u0e32\u0e19 \u0e1e\u0e2d\u0e42\u0e14\u0e19\u0e1d\u0e19\u0e14\u0e34\u0e19\u0e01\u0e47\u0e40\u0e09\u0e2d\u0e30\u0e41\u0e09\u0e30\u0e40\u0e2b\u0e22\u0e35\u0e22\u0e1a\u0e25\u0e07\u0e44\u0e1b\u0e08\u0e30\u0e15\u0e34\u0e14\u0e40\u0e17\u0e49\u0e32 \u0e40\u0e14\u0e34\u0e19\u0e2a\u0e31\u0e01\u0e22\u0e35\u0e48\u0e2a\u0e34\u0e1a\u0e01\u0e49\u0e32\u0e27\u0e01\u0e47\u0e08\u0e30\u0e21\u0e35\u0e14\u0e34\u0e19\u0e15\u0e34\u0e14\u0e40\u0e17\u0e49\u0e32\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13\u0e02\u0e49\u0e32\u0e07\u0e25\u0e30\u0e01\u0e34\u0e42\u0e25\u0e01\u0e23\u0e31\u0e21 \u0e41\u0e15\u0e48\u0e44\u0e21\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e16\u0e36\u0e07\u0e22\u0e35\u0e48\u0e2a\u0e34\u0e1a\u0e01\u0e49\u0e32\u0e27\u0e2b\u0e23\u0e2d\u0e01 \u0e40\u0e1e\u0e35\u0e22\u0e07\u0e40\u0e14\u0e34\u0e19\u0e44\u0e1b\u0e2a\u0e35\u0e48\u0e2b\u0e49\u0e32\u0e01\u0e49\u0e32\u0e27\u0e14\u0e34\u0e19\u0e01\u0e47\u0e08\u0e30\u0e15\u0e34\u0e14\u0e40\u0e17\u0e49\u0e32\u0e08\u0e19\u0e40\u0e14\u0e34\u0e19\u0e22\u0e32\u0e01\u0e44\u0e21\u0e48\u0e2d\u0e22\u0e32\u0e01\u0e40\u0e14\u0e34\u0e19 \u0e25\u0e49\u0e32\u0e07\u0e2d\u0e2d\u0e01\u0e01\u0e47\u0e22\u0e32\u0e01 \u0e15\u0e49\u0e2d\u0e07\u0e19\u0e31\u0e48\u0e07\u0e41\u0e04\u0e30\u0e22\u0e37\u0e19\u0e41\u0e04\u0e30 \u0e23\u0e32\u0e14\u0e19\u0e49\u0e33\u0e41\u0e25\u0e49\u0e27\u0e16\u0e39\u0e01\u0e47\u0e22\u0e31\u0e07\u0e44\u0e21\u0e48\u0e22\u0e2d\u0e21\u0e2d\u0e2d\u0e01\u0e07\u0e48\u0e32\u0e22\u0e46 \u0e25\u0e49\u0e32\u0e07\u0e40\u0e17\u0e49\u0e32\u0e04\u0e23\u0e31\u0e49\u0e07\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e19\u0e49\u0e33\u0e2b\u0e21\u0e14\u0e44\u0e1b\u0e04\u0e23\u0e36\u0e48\u0e07\u0e15\u0e38\u0e48\u0e21 \u0e04\u0e23\u0e31\u0e49\u0e19\u0e08\u0e30\u0e17\u0e33\u0e2d\u0e48\u0e32\u0e07\u0e25\u0e49\u0e32\u0e07\u0e40\u0e17\u0e49\u0e32\u0e44\u0e27\u0e49\u0e40\u0e0a\u0e34\u0e07\u0e1a\u0e31\u0e19\u0e44\u0e14\u0e41\u0e1a\u0e1a\u0e1a\u0e49\u0e32\u0e19\u0e44\u0e17\u0e22\u0e42\u0e1a\u0e23\u0e32\u0e13\u0e19\u0e34\u0e22\u0e21 \u0e1e\u0e2d\u0e25\u0e07\u0e44\u0e1b\u0e25\u0e49\u0e32\u0e07\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e04\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27\u0e14\u0e34\u0e19\u0e01\u0e47\u0e15\u0e01\u0e25\u0e07\u0e44\u0e1b\u0e43\u0e19\u0e2d\u0e48\u0e32\u0e07\u0e21\u0e32\u0e01\u0e08\u0e19\u0e19\u0e49\u0e33\u0e02\u0e38\u0e48\u0e19 \u0e04\u0e19\u0e15\u0e48\u0e2d\u0e44\u0e1b\u0e44\u0e21\u0e48\u0e2d\u0e22\u0e32\u0e01\u0e25\u0e07\u0e25\u0e49\u0e32\u0e07 \u0e2b\u0e19\u0e49\u0e32\u0e1d\u0e19\u0e40\u0e23\u0e32\u0e01\u0e47\u0e40\u0e25\u0e22\u0e41\u0e17\u0e1a\u0e44\u0e21\u0e48\u0e2d\u0e22\u0e32\u0e01\u0e25\u0e07\u0e08\u0e32\u0e01\u0e1a\u0e49\u0e32\u0e19\u0e44\u0e1b\u0e44\u0e2b\u0e19 \u0e19\u0e35\u0e48\u0e2b\u0e21\u0e32\u0e22\u0e16\u0e36\u0e07\u0e1b\u0e35\u0e41\u0e23\u0e01\u0e2d\u0e22\u0e39\u0e48\u0e1a\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e23\u0e37\u0e2d\u0e19\u0e41\u0e23\u0e01\u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e23\u0e31\u0e27\u0e1a\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e2a\u0e23\u0e23\u0e1e \u0e1e\u0e2d\u0e1b\u0e35\u0e17\u0e35\u0e48\u0e2a\u0e2d\u0e07\u0e40\u0e23\u0e32\u0e21\u0e35\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e2d\u0e35\u0e01\u0e2b\u0e25\u0e31\u0e07\u0e2b\u0e19\u0e36\u0e48\u0e07 \u0e0a\u0e37\u0e48\u0e2d\u0e40\u0e23\u0e37\u0e2d\u0e19\u0e40\u0e2a\u0e07\u0e35\u0e48\u0e22\u0e21\u0e40\u0e2a\u0e21\u0e2d \u0e2d\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u0e2a\u0e38\u0e25\u0e31\u0e01\u0e29\u0e13\u0e4c\u0e15\u0e31\u0e49\u0e07\u0e0a\u0e37\u0e48\u0e2d\u0e15\u0e32\u0e21\u0e19\u0e32\u0e21\u0e21.\u0e23.\u0e27.\u0e40\u0e2a\u0e07\u0e35\u0e48\u0e22\u0e21 \u0e2a\u0e19\u0e34\u0e17\u0e27\u0e07\u0e28\u0e4c \u0e04\u0e38\u0e13\u0e22\u0e48\u0e32\u0e1e\u0e35\u0e48\u0e2b\u0e19\u0e48\u0e2d\u0e22 (\u0e21.\u0e23.\u0e27.\u0e2a\u0e32\u0e22\u0e2a\u0e27\u0e31\u0e2a\u0e14\u0e35 \u0e2a\u0e27\u0e31\u0e2a\u0e14\u0e34\u0e27\u0e31\u0e15\u0e19\u0e4c) \u0e41\u0e25\u0e30\u0e2b\u0e21\u0e48\u0e2d\u0e21\u0e40\u0e2a\u0e21\u0e2d \u0e2a\u0e27\u0e31\u0e2a\u0e14\u0e34\u0e27\u0e31\u0e15\u0e19\u0e4c \u0e21\u0e32\u0e23\u0e14\u0e32\u0e1e\u0e35\u0e48\u0e2b\u0e19\u0e48\u0e2d\u0e22 \u0e40\u0e1b\u0e47\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35\u0e43\u0e15\u0e49\u0e16\u0e38\u0e19\u0e2a\u0e39\u0e07 \u0e17\u0e33\u0e04\u0e23\u0e31\u0e27\u0e02\u0e49\u0e32\u0e07\u0e25\u0e48\u0e32\u0e07 \u0e01\u0e25\u0e32\u0e07\u0e27\u0e31\u0e19\u0e01\u0e47\u0e44\u0e21\u0e48\u0e21\u0e35\u0e43\u0e04\u0e23\u0e02\u0e36\u0e49\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e25\u0e22\u0e40\u0e1e\u0e23\u0e32\u0e30\u0e02\u0e35\u0e49\u0e40\u0e01\u0e35\u0e22\u0e08\u0e25\u0e49\u0e32\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e15\u0e37\u0e48\u0e19\u0e40\u0e0a\u0e49\u0e32\u0e25\u0e07\u0e21\u0e32\u0e17\u0e33\u0e07\u0e32\u0e19\u0e22\u0e48\u0e33\u0e44\u0e1b\u0e22\u0e48\u0e33\u0e21\u0e32\u0e08\u0e19\u0e04\u0e48\u0e33\u0e16\u0e36\u0e07\u0e40\u0e27\u0e25\u0e32\u0e19\u0e2d\u0e19\u0e42\u0e19\u0e48\u0e19\u0e41\u0e2b\u0e25\u0e30\u0e08\u0e36\u0e07\u0e25\u0e49\u0e32\u0e07\u0e40\u0e17\u0e49\u0e32\u0e02\u0e36\u0e49\u0e19\u0e1a\u0e49\u0e32\u0e19<\/p><\/td><\/tr><\/tbody><\/table>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\u0e19\u0e49\u0e33\u0e43\u0e19\u0e04\u0e25\u0e2d\u0e07\u0e40\u0e23\u0e34\u0e48\u0e21\u0e44\u0e2b\u0e25\u0e40\u0e23\u0e47\u0e27\u0e41\u0e25\u0e30\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e19\u0e49\u0e33\u0e2a\u0e39\u0e07\u0e02\u0e36\u0e49\u0e19\u0e17\u0e38\u0e01\u0e27\u0e31\u0e19 \u0e40\u0e23\u0e32\u0e40\u0e23\u0e34\u0e48\u0e21\u0e16\u0e39\u0e01\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34\u0e17\u0e14\u0e2a\u0e2d\u0e1a\u0e1d\u0e35\u0e21\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e1e\u0e32\u0e22\u0e40\u0e23\u0e37\u0e2d\u0e27\u0e48\u0e32\u0e43\u0e0a\u0e49\u0e01\u0e32\u0e23\u0e44\u0e14\u0e49\u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e31\u0e07\u0e15\u0e2d\u0e19\u0e19\u0e35\u0e49\u0e40\u0e23\u0e32\u0e21\u0e35\u0e40\u0e23\u0e37\u0e2d\u0e25\u0e33\u0e40\u0e25\u0e47\u0e01\u0e17\u0e35\u0e48\u0e08\u0e49\u0e32\u0e07\u0e0a\u0e48\u0e32\u0e07\u0e15\u0e48\u0e2d 1 \u0e25\u0e33 \u0e01\u0e48\u0e2d\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e19\u0e35\u0e49\u0e40\u0e23\u0e32\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e40\u0e23\u0e37\u0e2d\u0e1b\u0e49\u0e32\u0e41\u0e14\u0e07 \u0e41\u0e23\u0e01\u0e46 \u0e17\u0e35\u0e48\u0e40\u0e23\u0e34\u0e48\u0e21\u0e21\u0e35\u0e01\u0e23\u0e30\u0e41\u0e2a\u0e19\u0e49\u0e33\u0e40\u0e0a\u0e35\u0e48\u0e22\u0e27\u0e40\u0e23\u0e32\u0e01\u0e47\u0e44\u0e21\u0e48\u0e04\u0e48\u0e2d\u0e22\u0e21\u0e31\u0e48\u0e19\u0e43\u0e08\u0e19\u0e31\u0e01\u0e27\u0e48\u0e32\u0e08\u0e30\u0e1e\u0e32\u0e22\u0e40\u0e23\u0e37\u0e2d\u0e02\u0e49\u0e32\u0e21\u0e1d\u0e31\u0e48\u0e07\u0e44\u0e14\u0e49\u0e15\u0e23\u0e07\u0e08\u0e38\u0e14\u0e44\u0e2b\u0e19 &hellip; <a href=\"https:\/\/wongsanit-ashram.org\/2019\/2017\/05\/13\/trawainaiduangjit10\/\" class=\"more-link\"><span>Continue reading<span class=\"screen-reader-text\">\u0e15\u0e23\u0e32\u0e44\u0e27\u0e49\u0e43\u0e19\u0e14\u0e27\u0e07\u0e08\u0e34\u0e15 \u0e15\u0e2d\u0e1910<\/span><\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":664,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-702","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-1"],"_links":{"self":[{"href":"https:\/\/wongsanit-ashram.org\/2019\/wp-json\/wp\/v2\/posts\/702","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wongsanit-ashram.org\/2019\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wongsanit-ashram.org\/2019\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wongsanit-ashram.org\/2019\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wongsanit-ashram.org\/2019\/wp-json\/wp\/v2\/comments?post=702"}],"version-history":[{"count":5,"href":"https:\/\/wongsanit-ashram.org\/2019\/wp-json\/wp\/v2\/posts\/702\/revisions"}],"predecessor-version":[{"id":838,"href":"https:\/\/wongsanit-ashram.org\/2019\/wp-json\/wp\/v2\/posts\/702\/revisions\/838"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wongsanit-ashram.org\/2019\/wp-json\/wp\/v2\/media\/664"}],"wp:attachment":[{"href":"https:\/\/wongsanit-ashram.org\/2019\/wp-json\/wp\/v2\/media?parent=702"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wongsanit-ashram.org\/2019\/wp-json\/wp\/v2\/categories?post=702"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wongsanit-ashram.org\/2019\/wp-json\/wp\/v2\/tags?post=702"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}